{"id":5937,"date":"2022-04-01T19:19:27","date_gmt":"2022-04-01T17:19:27","guid":{"rendered":"https:\/\/lyonbiopole.com\/formulaire-dadhesion-a-lyonbiopole"},"modified":"2022-05-27T14:34:21","modified_gmt":"2022-05-27T12:34:21","slug":"lyonbiopole-membership-form","status":"publish","type":"page","link":"https:\/\/lyonbiopole.com\/en\/lyonbiopole\/become-a-member-or-associate-member\/lyonbiopole-membership-form","title":{"rendered":"Lyonbiopole membership form"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":5939,"menu_order":96,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-5937","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lyonbiopole membership form - Lyonbiop\u00f4le<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lyonbiopole.com\/en\/lyonbiopole\/become-a-member-or-associate-member\/lyonbiopole-membership-form\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lyonbiopole membership form - Lyonbiop\u00f4le\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lyonbiopole.com\/en\/lyonbiopole\/become-a-member-or-associate-member\/lyonbiopole-membership-form\" \/>\n<meta property=\"og:site_name\" content=\"Lyonbiop\u00f4le\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-27T12:34:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lyonbiopole.com\\\/en\\\/lyonbiopole\\\/become-a-member-or-associate-member\\\/lyonbiopole-membership-form\",\"url\":\"https:\\\/\\\/lyonbiopole.com\\\/en\\\/lyonbiopole\\\/become-a-member-or-associate-member\\\/lyonbiopole-membership-form\",\"name\":\"Lyonbiopole membership form - Lyonbiop\u00f4le\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyonbiopole.com\\\/#website\"},\"datePublished\":\"2022-04-01T17:19:27+00:00\",\"dateModified\":\"2022-05-27T12:34:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lyonbiopole.com\\\/en\\\/lyonbiopole\\\/become-a-member-or-associate-member\\\/lyonbiopole-membership-form#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lyonbiopole.com\\\/en\\\/lyonbiopole\\\/become-a-member-or-associate-member\\\/lyonbiopole-membership-form\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lyonbiopole.com\\\/en\\\/lyonbiopole\\\/become-a-member-or-associate-member\\\/lyonbiopole-membership-form#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lyonbiopole\",\"item\":\"https:\\\/\\\/lyonbiopole.com\\\/en\\\/lyonbiopole\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Become a member or associate member\",\"item\":\"https:\\\/\\\/lyonbiopole.com\\\/en\\\/lyonbiopole\\\/become-a-member-or-associate-member\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lyonbiopole membership form\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lyonbiopole.com\\\/#website\",\"url\":\"https:\\\/\\\/lyonbiopole.com\\\/\",\"name\":\"Lyonbiop\u00f4le\",\"description\":\"Le r\u00e9seau innovation sant\u00e9 de la r\u00e9gion Auvergne Rh\u00f4ne-Alpes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lyonbiopole.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lyonbiopole membership form - Lyonbiop\u00f4le","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lyonbiopole.com\/en\/lyonbiopole\/become-a-member-or-associate-member\/lyonbiopole-membership-form","og_locale":"en_US","og_type":"article","og_title":"Lyonbiopole membership form - Lyonbiop\u00f4le","og_url":"https:\/\/lyonbiopole.com\/en\/lyonbiopole\/become-a-member-or-associate-member\/lyonbiopole-membership-form","og_site_name":"Lyonbiop\u00f4le","article_modified_time":"2022-05-27T12:34:21+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lyonbiopole.com\/en\/lyonbiopole\/become-a-member-or-associate-member\/lyonbiopole-membership-form","url":"https:\/\/lyonbiopole.com\/en\/lyonbiopole\/become-a-member-or-associate-member\/lyonbiopole-membership-form","name":"Lyonbiopole membership form - Lyonbiop\u00f4le","isPartOf":{"@id":"https:\/\/lyonbiopole.com\/#website"},"datePublished":"2022-04-01T17:19:27+00:00","dateModified":"2022-05-27T12:34:21+00:00","breadcrumb":{"@id":"https:\/\/lyonbiopole.com\/en\/lyonbiopole\/become-a-member-or-associate-member\/lyonbiopole-membership-form#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lyonbiopole.com\/en\/lyonbiopole\/become-a-member-or-associate-member\/lyonbiopole-membership-form"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lyonbiopole.com\/en\/lyonbiopole\/become-a-member-or-associate-member\/lyonbiopole-membership-form#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lyonbiopole","item":"https:\/\/lyonbiopole.com\/en\/lyonbiopole"},{"@type":"ListItem","position":2,"name":"Become a member or associate member","item":"https:\/\/lyonbiopole.com\/en\/lyonbiopole\/become-a-member-or-associate-member"},{"@type":"ListItem","position":3,"name":"Lyonbiopole membership form"}]},{"@type":"WebSite","@id":"https:\/\/lyonbiopole.com\/#website","url":"https:\/\/lyonbiopole.com\/","name":"Lyonbiop\u00f4le","description":"Le r\u00e9seau innovation sant\u00e9 de la r\u00e9gion Auvergne Rh\u00f4ne-Alpes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lyonbiopole.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/lyonbiopole.com\/en\/wp-json\/wp\/v2\/pages\/5937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonbiopole.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lyonbiopole.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lyonbiopole.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonbiopole.com\/en\/wp-json\/wp\/v2\/comments?post=5937"}],"version-history":[{"count":0,"href":"https:\/\/lyonbiopole.com\/en\/wp-json\/wp\/v2\/pages\/5937\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/lyonbiopole.com\/en\/wp-json\/wp\/v2\/pages\/5939"}],"wp:attachment":[{"href":"https:\/\/lyonbiopole.com\/en\/wp-json\/wp\/v2\/media?parent=5937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}